{"id":18036,"date":"2025-12-11T10:26:00","date_gmt":"2025-12-11T11:26:00","guid":{"rendered":"https:\/\/ipc.cv\/?post_type=noticias&#038;p=18036"},"modified":"2026-01-27T10:27:59","modified_gmt":"2026-01-27T11:27:59","slug":"6-anos-da-elevacao-da-morna-a-patrimonio-cultural-imaterial-da-humanidade","status":"publish","type":"noticias","link":"https:\/\/ipc.cv\/fr\/noticias\/6-anos-da-elevacao-da-morna-a-patrimonio-cultural-imaterial-da-humanidade\/","title":{"rendered":"6 anos da eleva\u00e7\u00e3o da Morna a Patrim\u00f3nio Cultural Imaterial da Humanidade."},"content":{"rendered":"<p>\u201cA salvaguarda da morna n\u00e3o \u00e9 apenas uma obriga\u00e7\u00e3o do Estado, \u00e9 acima de tudo, uma miss\u00e3o coletiva\u201d \u2013 MCIC, Augusto Veiga<\/p>\n\n\n\n<p>Celebra-se hoje, 11 de dezembro, o 6\u00ba anivers\u00e1rio da eleva\u00e7\u00e3o da Morna a Patrim\u00f3nio Cultural Imaterial da Humanidade, o dia em que a Morna foi inscrita \u201cna alma da humanidade\u201d.<\/p>\n\n\n\n<p>Neste dia de celebra\u00e7\u00e3o, o Minist\u00e9rio da Cultura e das Ind\u00fastrias Criativas, atrav\u00e9s do Instituto do Patrim\u00f3nio Cultural (IPC), promoveu o workshop \u201cO papel do poder local e das associa\u00e7\u00f5es comunit\u00e1rias de m\u00fasica na salvaguarda da Morna\u201d.<\/p>\n\n\n\n<p>Importa, todos os anos, assinalar esta data enquanto conquista hist\u00f3rica das comunidades da morna, dos professores, das organiza\u00e7\u00f5es da sociedade civil e de todos os cabo-verdianos, no pa\u00eds e na di\u00e1spora, que t\u00eam contribu\u00eddo, de forma incans\u00e1vel, para a valoriza\u00e7\u00e3o, transmiss\u00e3o e perpetua\u00e7\u00e3o da Morna.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"18038\" src=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/597277430_1289512416554499_4525414625041724359_n-1024x683.jpg\" alt=\"\" class=\"wp-image-18038\" srcset=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/597277430_1289512416554499_4525414625041724359_n-1024x683.jpg 1024w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/597277430_1289512416554499_4525414625041724359_n-300x200.jpg 300w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/597277430_1289512416554499_4525414625041724359_n-768x512.jpg 768w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/597277430_1289512416554499_4525414625041724359_n-1536x1024.jpg 1536w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/597277430_1289512416554499_4525414625041724359_n-18x12.jpg 18w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/597277430_1289512416554499_4525414625041724359_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"18040\" src=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/595914154_1289512403221167_1843779132971111517_n-1024x683.jpg\" alt=\"\" class=\"wp-image-18040\" srcset=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/595914154_1289512403221167_1843779132971111517_n-1024x683.jpg 1024w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/595914154_1289512403221167_1843779132971111517_n-300x200.jpg 300w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/595914154_1289512403221167_1843779132971111517_n-768x512.jpg 768w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/595914154_1289512403221167_1843779132971111517_n-1536x1024.jpg 1536w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/595914154_1289512403221167_1843779132971111517_n-18x12.jpg 18w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/595914154_1289512403221167_1843779132971111517_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"18039\" src=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594286324_1289512269887847_6174048548008600836_n-1024x683.jpg\" alt=\"\" class=\"wp-image-18039\" srcset=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594286324_1289512269887847_6174048548008600836_n-1024x683.jpg 1024w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594286324_1289512269887847_6174048548008600836_n-300x200.jpg 300w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594286324_1289512269887847_6174048548008600836_n-768x512.jpg 768w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594286324_1289512269887847_6174048548008600836_n-1536x1024.jpg 1536w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594286324_1289512269887847_6174048548008600836_n-18x12.jpg 18w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594286324_1289512269887847_6174048548008600836_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>A eleva\u00e7\u00e3o da Morna a Patrim\u00f3nio Mundial, em 2019, constituiu um marco de enorme significado para Cabo Verde, representando o reconhecimento internacional de uma express\u00e3o profunda da nossa alma coletiva, da nossa mem\u00f3ria e da nossa identidade enquanto povo.<\/p>\n\n\n\n<p>Este feito foi fruto de um trabalho coletivo e persistente, liderado pelas institui\u00e7\u00f5es culturais, mas sustentado pela comunidade da Morna, que nunca permitiu que esta heran\u00e7a se perdesse no tempo.<\/p>\n\n\n\n<p>\u201cA salvaguarda da Morna n\u00e3o \u00e9 apenas uma obriga\u00e7\u00e3o do Estado \u00e9, acima de tudo, uma miss\u00e3o coletiva. \u00c9 um compromisso que une o poder p\u00fablico, a sociedade civil, o setor privado, os artistas e os educadores\u201d, destacou o MCIC, Augusto Veiga.<\/p>\n\n\n\n<p>O MCIC, atrav\u00e9s do IPC e de outras iniciativas, tem desenvolvido um conjunto de a\u00e7\u00f5es de promo\u00e7\u00e3o, valoriza\u00e7\u00e3o e transmiss\u00e3o da Morna. Para al\u00e9m disso, o Plano de Salvaguarda da Morna come\u00e7ar\u00e1 a ser implementado muito em breve.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"18041\" src=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/598386418_1289512723221135_828430511740249492_n-1024x683.jpg\" alt=\"\" class=\"wp-image-18041\" srcset=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/598386418_1289512723221135_828430511740249492_n-1024x683.jpg 1024w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/598386418_1289512723221135_828430511740249492_n-300x200.jpg 300w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/598386418_1289512723221135_828430511740249492_n-768x512.jpg 768w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/598386418_1289512723221135_828430511740249492_n-1536x1024.jpg 1536w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/598386418_1289512723221135_828430511740249492_n-18x12.jpg 18w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/598386418_1289512723221135_828430511740249492_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"18042\" src=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594856369_1289512456554495_2721988250317275302_n-1024x683.jpg\" alt=\"\" class=\"wp-image-18042\" srcset=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594856369_1289512456554495_2721988250317275302_n-1024x683.jpg 1024w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594856369_1289512456554495_2721988250317275302_n-300x200.jpg 300w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594856369_1289512456554495_2721988250317275302_n-768x512.jpg 768w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594856369_1289512456554495_2721988250317275302_n-1536x1024.jpg 1536w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594856369_1289512456554495_2721988250317275302_n-18x12.jpg 18w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/594856369_1289512456554495_2721988250317275302_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"18043\" src=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/596508689_1289512349887839_219004395889032532_n-1024x683.jpg\" alt=\"\" class=\"wp-image-18043\" srcset=\"https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/596508689_1289512349887839_219004395889032532_n-1024x683.jpg 1024w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/596508689_1289512349887839_219004395889032532_n-300x200.jpg 300w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/596508689_1289512349887839_219004395889032532_n-768x512.jpg 768w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/596508689_1289512349887839_219004395889032532_n-1536x1024.jpg 1536w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/596508689_1289512349887839_219004395889032532_n-18x12.jpg 18w, https:\/\/ipc.cv\/wp-content\/uploads\/2026\/01\/596508689_1289512349887839_219004395889032532_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>\u201cA salvaguarda da morna n\u00e3o \u00e9 apenas uma obriga\u00e7\u00e3o do Estado, \u00e9 acima de tudo, uma miss\u00e3o coletiva\u201d \u2013 MCIC, Augusto Veiga Celebra-se hoje, 11 de dezembro, o 6\u00ba anivers\u00e1rio da eleva\u00e7\u00e3o da Morna a Patrim\u00f3nio Cultural Imaterial da Humanidade, o dia em que a Morna foi inscrita \u201cna alma da humanidade\u201d. Neste dia de [&hellip;]<\/p>\n","protected":false},"featured_media":18037,"template":"","meta":[],"tags":[],"class_list":["post-18036","noticias","type-noticias","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/ipc.cv\/fr\/wp-json\/wp\/v2\/noticias\/18036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipc.cv\/fr\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/ipc.cv\/fr\/wp-json\/wp\/v2\/types\/noticias"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ipc.cv\/fr\/wp-json\/wp\/v2\/media\/18037"}],"wp:attachment":[{"href":"https:\/\/ipc.cv\/fr\/wp-json\/wp\/v2\/media?parent=18036"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipc.cv\/fr\/wp-json\/wp\/v2\/tags?post=18036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}